{"id":3158,"date":"2021-07-28T13:37:08","date_gmt":"2021-07-28T11:37:08","guid":{"rendered":"https:\/\/baynana.es\/?p=3158"},"modified":"2022-02-23T13:45:20","modified_gmt":"2022-02-23T12:45:20","slug":"barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes","status":"publish","type":"post","link":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/","title":{"rendered":"Barzakh, entre mundos, una exposici\u00f3n fotogr\u00e1fica muestra la realidad de la juventud en el Magreb a trav\u00e9s de im\u00e1genes"},"content":{"rendered":"\n<p dir=\"ltr\"><a href=\"https:\/\/twitter.com\/ayham_greeb\" target=\"_blank\" rel=\"noreferrer noopener\">Ayham Gareeb<\/a> &#8211; <a href=\"https:\/\/twitter.com\/mohammed_shobat\" target=\"_blank\" rel=\"noreferrer noopener\">Mohammad Shubat<\/a><\/p>\n\n\n\n<p dir=\"ltr\"><a href=\"https:\/\/www.casaarabe.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Casa \u00c1rabe<\/a> y <a href=\"https:\/\/www.phe.es\/festivalphe\/\" target=\"_blank\" rel=\"noreferrer noopener\">PhotoEspa\u00f1a<\/a> organizan una exposici\u00f3n de arte que se exhibe desde el 1 de junio de 2021 hasta el 17 de octubre de 2021. Incluye fotograf\u00edas de ocho autores del Magreb (Norte de \u00c1frica). Bajo el t\u00edtulo \u00ab<strong>Barzakh<\/strong>\u00ab, que significa \u201cel limbo, o el estado entre dos cosas\u201d. En el Cor\u00e1n, es el intervalo entre la muerte y el d\u00eda del juicio final. Con la exposici\u00f3n \u201c<strong>Barzakh<\/strong>\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed: de Marruecos, Argelia, T\u00fanez y Libia, a trav\u00e9s de im\u00e1genes presentadas por los artistas participantes.<\/p>\n\n\n\n<p dir=\"ltr\">Este proyecto fue seleccionado por el jurado de la \u201cconvocatoria NUR\u201d y est\u00e1 patrocinado por Xavier de Luca y Houari Bouchnak.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-1024x681.jpg\" alt=\"\" class=\"wp-image-3150\" srcset=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-1024x681.jpg 1024w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-600x399.jpg 600w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-300x200.jpg 300w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-768x511.jpg 768w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-1536x1022.jpg 1536w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4185-2048x1363.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Algunas de las pinturas que se exhiben en la exposici\u00f3n de Barzakh en la sede de Casa \u00c1rabe en Madrid \u00a9 Mohammad Shubat<\/figcaption><\/figure>\n\n\n\n<p dir=\"ltr\">En <strong>Baynana <\/strong>nos hemos reunido con El argelino <strong>Houari Bouchnak, <\/strong>uno de los patrocinadores de esta exposici\u00f3n,<strong> <\/strong>para hablar sobre este proyecto, que ha sido una oportunidad para mostrar la huella dactilar del Magreb, y la realidad de la vida de los j\u00f3venes y de las asociaciones que trabajan con la juventud. \u00abHablamos mucho de Marruecos, Argelia, T\u00fanez y Libia, pero por ejemplo el argelino no sabe lo que hay en Marruecos, y el marroqu\u00ed tampoco sabe, y mucho menos hablar de ello a la audiencia europea, no saben nada, excepto cosas simples de los medios \u201d, <strong>dice<\/strong> <strong>Bouchnak.<\/strong><\/p>\n\n\n\n<p dir=\"ltr\" style=\"font-size:18px\"><strong><span style=\"color:#ec4e35\" class=\"has-inline-color\">Diferentes sonidos, pero se parecen<\/span><\/strong><\/p>\n\n\n\n<p dir=\"ltr\">\u00ab<strong>Barzakh<\/strong>\u00bb muestra obras de ocho artistas de<strong> <\/strong>T\u00fanez, Marruecos<strong> <\/strong>y Argelia: <strong>Ziad Ben Ramadan<\/strong>, <strong>Souad Mani<\/strong>, <strong>Hakim Razaoui<\/strong>, <strong>Yasmine Hatami<\/strong>, <strong>Sonia Merabet<\/strong>, <strong>Mohamed Kilito<\/strong>, <strong>Tony Serra Abu Ali<\/strong> y <strong>Abdo Shanan<\/strong>. Esta exposici\u00f3n tambi\u00e9n recoge obras de cinco asociaciones independientes de Argelia,T\u00fanez, Marruecos y Espa\u00f1a: <a href=\"https:\/\/www.jiser.org\/es\/project\/barzakh-entremundos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Colectivo KOZ<\/strong><\/a>, <a href=\"https:\/\/www.collective220.net\/\"><strong>Colectivo 220<\/strong><\/a><strong>,<\/strong> <a href=\"https:\/\/rhizome.gallery\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Rizoma<\/strong><\/a>, <a href=\"https:\/\/maisonimage.tn\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Maison de l&#8217;Image<\/strong><\/a> y <a href=\"https:\/\/www.jiser.org\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Jiser<\/strong><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-1024x681.jpg\" alt=\"\" class=\"wp-image-3156\" srcset=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-1024x681.jpg 1024w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-600x399.jpg 600w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-300x200.jpg 300w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-768x511.jpg 768w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-1536x1022.jpg 1536w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4193-2048x1363.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Visitante de la exposici\u00f3n Barzakh en la sede de la Casa \u00c1rabe en Madrid \u00a9 Mohammad Shubat<\/figcaption><\/figure>\n\n\n\n<p dir=\"ltr\">Cuando accedes a la exposici\u00f3n \u201c<strong>Barzakh<\/strong>\u201d encuentras que las obras son iguales, y no sientes que hay una voz m\u00e1s alta que otra. \u201cSientes que todas las voces caminan juntas en la misma l\u00ednea. Hay una expresi\u00f3n com\u00fan para diferentes temas, en el origen de uno para los\u00a0dem\u00e1s. Creo que esa es una de las fortalezas que hab\u00eda en el proyecto\u201d, declara el fot\u00f3grafo argelino <strong>Abdo Al-Shanan<\/strong>, que particip\u00f3 en esta exposici\u00f3n.<\/p>\n\n\n\n<p dir=\"ltr\" style=\"font-size:18px\"><strong><span style=\"color:#ec4e35\" class=\"has-inline-color\">Espacios c\u00f3smicos<\/span><\/strong><\/p>\n\n\n\n<p dir=\"ltr\">Los participantes distribuyen sus obras en varios espacios de la Casa \u00c1rabe. Uno de ellos se llama \u201cel espacio en blanco\u201d porque incluye fotograf\u00edas del fot\u00f3grafo tunecino Tony Serra, fallecido en 2019. En el mismo, hay fotograf\u00edas tambi\u00e9n del fot\u00f3grafo tunecino <strong>Ziad Ramad\u00e1n<\/strong>, quien refleja la verdadera imagen de los j\u00f3venes que trabajan en las minas en Gafsa, T\u00fanez. Es una zona remota y vac\u00eda, a donde acuden muchos j\u00f3venes de T\u00fanez, Libia y Argelia con el objetivo de buscar trabajo y recaudar fondos. El fot\u00f3grafo Sr. Ramad\u00e1n ha querido mostrar la situaci\u00f3n social de esta zona.\u00a0<\/p>\n\n\n\n<p dir=\"ltr\">Tambi\u00e9n participa el artista marroqu\u00ed <strong>Mohamed Kilto<\/strong>, cuyas\u00a0fotograf\u00edas reflejan la realidad de los j\u00f3venes marroqu\u00edes. Kilto ha ayudado a estos j\u00f3venes a trav\u00e9s de la fotograf\u00eda y entrevistas para crear un espacio en donde puedan expresar su opini\u00f3n. \u201cNo hay un espacio donde no puedan expresarse ni hablar. All\u00ed los j\u00f3venes no tienen voz, no pueden opinar, porque est\u00e1n oprimidos\u201d, dice<strong> Bouchnak<\/strong>.<\/p>\n\n\n\n<p dir=\"ltr\" style=\"font-size:18px\"><strong><span style=\"color:#ec4e35\" class=\"has-inline-color\">Recuerdos a trav\u00e9s de im\u00e1genes<\/span><\/strong><\/p>\n\n\n\n<p dir=\"ltr\"><strong>Abdo Al Shanan<\/strong> centra su participaci\u00f3n en la exposici\u00f3n<strong> \u201cBarzakh\u201d<\/strong> en recuerdos. Desde los m\u00e1s bellos hasta los duros y tr\u00e1gicos. El enfoque de Al Shanan tom\u00f3 forma despu\u00e9s de leer un libro llamado <strong>\u201cEl libro blanco\u201d, <\/strong>de una Asociaci\u00f3n de mujeres argelinas. Este libro contiene entrevistas a mujeres que fueron v\u00edctimas de violencia durante la Guerra Civil. Un ejemplo es la historia del secuestro de una ni\u00f1a por un terrorista, que fue obligada a cocinar para \u00e9l y otros terroristas. La cocina para ella es un recuerdo aterrador, mientras que para otros, puede ser delicioso por su sabor y olor. Estos recuerdos dependen de las vivencias y experiencias personales de cada uno.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-1024x681.jpg\" alt=\"\" class=\"wp-image-3154\" srcset=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-1024x681.jpg 1024w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-600x399.jpg 600w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-300x200.jpg 300w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-768x511.jpg 768w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-1536x1022.jpg 1536w, https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4214-2048x1363.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Una fotograf\u00eda de la exposici\u00f3n Barzakh refleja una imagen de una chica del Magreb \u00a9 Mohammad Shubat<\/figcaption><\/figure>\n\n\n\n<p dir=\"ltr\">El testimonio de esta mujer y de otras es lo que impuls\u00f3 a <strong>Al-Shannan<\/strong> a mostrar mediante la fotograf\u00eda sus vivencias y experiencias que relatan en <strong>\u201cEl libro blanco\u201d<\/strong>. \u201cEl objetivo no es crear la misma memoria de estas mujeres porque esto es imposible. M\u00e1s bien, transmitir el sentimiento que sent\u00edan estas mujeres. Quer\u00eda construir un puente entre el espectador, el p\u00fablico y los h\u00e9roes de estos cuentos\u201d, <strong>relata Al-Shanan.<\/strong><\/p>\n\n\n\n<p dir=\"ltr\">A trav\u00e9s de <strong>\u201cBarzakh\u201d<\/strong>, Al-Shanan quiso dejar claro que la violencia contra las mujeres no es solo violencia f\u00edsica sino tambi\u00e9n psicol\u00f3gica, y que perdura mucho en el tiempo. \u00abQuer\u00eda resaltar este reflejo de la violencia sobre las mujeres\u00bb, <strong>destaca el artista.\u00a0<\/strong> A su vez, <strong>Bouchnak <\/strong>concluy\u00f3 su entrevista don Baynana<strong> <\/strong>destacando que la exposici\u00f3n ha tenido buena acogida y una mirada positiva entre los visitantes permanentes de la Casa \u00c1rabe. Adem\u00e1s, esta exposici\u00f3n es el programa principal de PhotoEspa\u00f1a Festival, en donde tambi\u00e9n se expusieron la apertura de los videos de los fot\u00f3grafos que por la situaci\u00f3n covid-19 no han podido asistir para exponer sus trabajos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayham Gareeb &#8211; Mohammad Shubat Casa \u00c1rabe y PhotoEspa\u00f1a organizan una exposici\u00f3n de arte que se exhibe desde el 1 de junio de 2021 hasta el 17 de octubre de 2021. Incluye fotograf\u00edas de ocho autores del Magreb (Norte de \u00c1frica). Bajo el t\u00edtulo \u00abBarzakh\u00ab, que significa \u201cel limbo, o el estado entre dos cosas\u201d. &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[51,11,52],"tags":[370,91],"ppma_author":[503],"class_list":["post-3158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-y-cultura","category-inicio","category-reportajes","tag-la-exposicion","tag-revista-baynana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barzakh: im\u00e1genes que muestran la realidad de la juventud en el Magreb<\/title>\n<meta name=\"description\" content=\"Con la exposici\u00f3n \u201cBarzakh\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed a trav\u00e9s de im\u00e1genes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barzakh: im\u00e1genes que muestran la realidad de la juventud en el Magreb\" \/>\n<meta property=\"og:description\" content=\"Con la exposici\u00f3n \u201cBarzakh\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed a trav\u00e9s de im\u00e1genes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Baynana \u0628\u064a\u0646\u0646\u0627\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/baynanaes\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-28T11:37:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-23T12:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"baynana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-1-scaled.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@baynanaes\" \/>\n<meta name=\"twitter:site\" content=\"@baynanaes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"baynana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\"},\"author\":{\"name\":\"baynana\",\"@id\":\"https:\/\/baynana.es\/#\/schema\/person\/d743d5ffbf13ef7c04034c063666fe95\"},\"headline\":\"Barzakh, entre mundos, una exposici\u00f3n fotogr\u00e1fica muestra la realidad de la juventud en el Magreb a trav\u00e9s de im\u00e1genes\",\"datePublished\":\"2021-07-28T11:37:08+00:00\",\"dateModified\":\"2022-02-23T12:45:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\"},\"wordCount\":967,\"publisher\":{\"@id\":\"https:\/\/baynana.es\/#organization\"},\"image\":{\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg\",\"keywords\":[\"la exposici\u00f3n\",\"REVISTA BAYNANA\"],\"articleSection\":[\"HISTORIA Y CULTURA\",\"INICIO\",\"REPORTAJES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\",\"url\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\",\"name\":\"Barzakh: im\u00e1genes que muestran la realidad de la juventud en el Magreb\",\"isPartOf\":{\"@id\":\"https:\/\/baynana.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg\",\"datePublished\":\"2021-07-28T11:37:08+00:00\",\"dateModified\":\"2022-02-23T12:45:20+00:00\",\"description\":\"Con la exposici\u00f3n \u201cBarzakh\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed a trav\u00e9s de im\u00e1genes.\",\"breadcrumb\":{\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage\",\"url\":\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg\",\"contentUrl\":\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg\",\"width\":2560,\"height\":1703,\"caption\":\"Im\u00e1genes de un visitante a la exposici\u00f3n Barzakh\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/baynana.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barzakh, entre mundos, una exposici\u00f3n fotogr\u00e1fica muestra la realidad de la juventud en el Magreb a trav\u00e9s de im\u00e1genes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/baynana.es\/#website\",\"url\":\"https:\/\/baynana.es\/\",\"name\":\"Baynana \u0628\u064a\u0646\u0646\u0627\",\"description\":\"Baynana Revista \u0645\u062c\u0644\u0629 \u0628\u064a\u0646\u0646\u0627\",\"publisher\":{\"@id\":\"https:\/\/baynana.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/baynana.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/baynana.es\/#organization\",\"name\":\"\u0628\u064a\u0646\u0646\u0627 Baynana\",\"url\":\"https:\/\/baynana.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/baynana.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/03\/Artboard-1.png\",\"contentUrl\":\"https:\/\/baynana.es\/wp-content\/uploads\/2021\/03\/Artboard-1.png\",\"width\":315,\"height\":228,\"caption\":\"\u0628\u064a\u0646\u0646\u0627 Baynana\"},\"image\":{\"@id\":\"https:\/\/baynana.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/baynanaes\",\"https:\/\/x.com\/baynanaes\",\"https:\/\/www.instagram.com\/baynanaes\/\",\"https:\/\/www.linkedin.com\/in\/baynana-\u0628\u064a\u0646\u0646\u0627-887599211\/\",\"https:\/\/www.youtube.com\/channel\/UC3019bsq5wOpi61SOufKxPA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/baynana.es\/#\/schema\/person\/d743d5ffbf13ef7c04034c063666fe95\",\"name\":\"baynana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/baynana.es\/#\/schema\/person\/image\/2fdb3ad168978c52d9db4d0a4825fb0a\",\"url\":\"https:\/\/baynana.es\/wp-content\/uploads\/2022\/04\/baynana-A011-96x96.png\",\"contentUrl\":\"https:\/\/baynana.es\/wp-content\/uploads\/2022\/04\/baynana-A011-96x96.png\",\"caption\":\"baynana\"},\"description\":\"Baynana es un medio online biling\u00fce -en \u00e1rabe y espa\u00f1ol- que apuesta por el periodismo social y de servicio p\u00fablico. Nuestra revista aspira a ofrecer informaci\u00f3n de utilidad a la comunidad arab\u00f3fona en Espa\u00f1a y, al mismo tiempo, tender puentes entre las personas migrantes, refugiadas y espa\u00f1olas de origen extranjero, y el resto de la poblaci\u00f3n.\",\"sameAs\":[\"http:\/\/moussa\"],\"url\":\"https:\/\/baynana.es\/es\/author\/moussa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barzakh: im\u00e1genes que muestran la realidad de la juventud en el Magreb","description":"Con la exposici\u00f3n \u201cBarzakh\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed a trav\u00e9s de im\u00e1genes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/","og_locale":"es_ES","og_type":"article","og_title":"Barzakh: im\u00e1genes que muestran la realidad de la juventud en el Magreb","og_description":"Con la exposici\u00f3n \u201cBarzakh\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed a trav\u00e9s de im\u00e1genes.","og_url":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/","og_site_name":"Baynana \u0628\u064a\u0646\u0646\u0627","article_publisher":"https:\/\/www.facebook.com\/baynanaes","article_published_time":"2021-07-28T11:37:08+00:00","article_modified_time":"2022-02-23T12:45:20+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-1-scaled.jpg","type":"image\/jpeg"}],"author":"baynana","twitter_card":"summary_large_image","twitter_image":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-1-scaled.jpg","twitter_creator":"@baynanaes","twitter_site":"@baynanaes","twitter_misc":{"Escrito por":"baynana","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#article","isPartOf":{"@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/"},"author":{"name":"baynana","@id":"https:\/\/baynana.es\/#\/schema\/person\/d743d5ffbf13ef7c04034c063666fe95"},"headline":"Barzakh, entre mundos, una exposici\u00f3n fotogr\u00e1fica muestra la realidad de la juventud en el Magreb a trav\u00e9s de im\u00e1genes","datePublished":"2021-07-28T11:37:08+00:00","dateModified":"2022-02-23T12:45:20+00:00","mainEntityOfPage":{"@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/"},"wordCount":967,"publisher":{"@id":"https:\/\/baynana.es\/#organization"},"image":{"@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage"},"thumbnailUrl":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg","keywords":["la exposici\u00f3n","REVISTA BAYNANA"],"articleSection":["HISTORIA Y CULTURA","INICIO","REPORTAJES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/","url":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/","name":"Barzakh: im\u00e1genes que muestran la realidad de la juventud en el Magreb","isPartOf":{"@id":"https:\/\/baynana.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage"},"image":{"@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage"},"thumbnailUrl":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg","datePublished":"2021-07-28T11:37:08+00:00","dateModified":"2022-02-23T12:45:20+00:00","description":"Con la exposici\u00f3n \u201cBarzakh\u201d, emprendemos un viaje para explorar la condici\u00f3n humana de la juventud magreb\u00ed a trav\u00e9s de im\u00e1genes.","breadcrumb":{"@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#primaryimage","url":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg","contentUrl":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/07\/DSC_4212-scaled.jpg","width":2560,"height":1703,"caption":"Im\u00e1genes de un visitante a la exposici\u00f3n Barzakh"},{"@type":"BreadcrumbList","@id":"https:\/\/baynana.es\/es\/barzakh-entre-mundos-una-exposicion-fotografica-muestra-la-realidad-de-la-juventud-en-el-magreb-a-traves-de-imagenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/baynana.es\/es\/"},{"@type":"ListItem","position":2,"name":"Barzakh, entre mundos, una exposici\u00f3n fotogr\u00e1fica muestra la realidad de la juventud en el Magreb a trav\u00e9s de im\u00e1genes"}]},{"@type":"WebSite","@id":"https:\/\/baynana.es\/#website","url":"https:\/\/baynana.es\/","name":"Baynana \u0628\u064a\u0646\u0646\u0627","description":"Baynana Revista \u0645\u062c\u0644\u0629 \u0628\u064a\u0646\u0646\u0627","publisher":{"@id":"https:\/\/baynana.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/baynana.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/baynana.es\/#organization","name":"\u0628\u064a\u0646\u0646\u0627 Baynana","url":"https:\/\/baynana.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/baynana.es\/#\/schema\/logo\/image\/","url":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/03\/Artboard-1.png","contentUrl":"https:\/\/baynana.es\/wp-content\/uploads\/2021\/03\/Artboard-1.png","width":315,"height":228,"caption":"\u0628\u064a\u0646\u0646\u0627 Baynana"},"image":{"@id":"https:\/\/baynana.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/baynanaes","https:\/\/x.com\/baynanaes","https:\/\/www.instagram.com\/baynanaes\/","https:\/\/www.linkedin.com\/in\/baynana-\u0628\u064a\u0646\u0646\u0627-887599211\/","https:\/\/www.youtube.com\/channel\/UC3019bsq5wOpi61SOufKxPA"]},{"@type":"Person","@id":"https:\/\/baynana.es\/#\/schema\/person\/d743d5ffbf13ef7c04034c063666fe95","name":"baynana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/baynana.es\/#\/schema\/person\/image\/2fdb3ad168978c52d9db4d0a4825fb0a","url":"https:\/\/baynana.es\/wp-content\/uploads\/2022\/04\/baynana-A011-96x96.png","contentUrl":"https:\/\/baynana.es\/wp-content\/uploads\/2022\/04\/baynana-A011-96x96.png","caption":"baynana"},"description":"Baynana es un medio online biling\u00fce -en \u00e1rabe y espa\u00f1ol- que apuesta por el periodismo social y de servicio p\u00fablico. Nuestra revista aspira a ofrecer informaci\u00f3n de utilidad a la comunidad arab\u00f3fona en Espa\u00f1a y, al mismo tiempo, tender puentes entre las personas migrantes, refugiadas y espa\u00f1olas de origen extranjero, y el resto de la poblaci\u00f3n.","sameAs":["http:\/\/moussa"],"url":"https:\/\/baynana.es\/es\/author\/moussa\/"}]}},"authors":[{"term_id":503,"user_id":2,"is_guest":0,"slug":"moussa","display_name":"baynana","avatar_url":"https:\/\/baynana.es\/wp-content\/uploads\/2022\/04\/baynana-A011-96x96.png","author_category":"","first_name":"Moussa","last_name":"Al jamaat","user_url":"http:\/\/moussa","job_title":"","description":"Baynana es un medio online biling\u00fce -en \u00e1rabe y espa\u00f1ol- que apuesta por el periodismo social y de servicio p\u00fablico. Nuestra revista aspira a ofrecer informaci\u00f3n de utilidad a la comunidad arab\u00f3fona en Espa\u00f1a y, al mismo tiempo, tender puentes entre las personas migrantes, refugiadas y espa\u00f1olas de origen extranjero, y el resto de la poblaci\u00f3n."}],"_links":{"self":[{"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/posts\/3158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/comments?post=3158"}],"version-history":[{"count":1,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/posts\/3158\/revisions"}],"predecessor-version":[{"id":4918,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/posts\/3158\/revisions\/4918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/media\/3152"}],"wp:attachment":[{"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/media?parent=3158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/categories?post=3158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/tags?post=3158"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/baynana.es\/es\/wp-json\/wp\/v2\/ppma_author?post=3158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}